{"id":483,"count":1,"description":"","link":"http:\/\/www.biblionalia.info\/leah\/blog\/tag\/two-ravens\/","name":"two ravens","slug":"two-ravens","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.biblionalia.info\/leah\/wp-json\/wp\/v2\/tags\/483"}],"collection":[{"href":"http:\/\/www.biblionalia.info\/leah\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.biblionalia.info\/leah\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.biblionalia.info\/leah\/wp-json\/wp\/v2\/posts?tags=483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}